{"id":1688,"date":"2023-10-26T20:20:49","date_gmt":"2023-10-27T00:20:49","guid":{"rendered":"https:\/\/www.ebc.gob.bo\/portal\/?p=1688"},"modified":"2023-10-27T09:57:08","modified_gmt":"2023-10-27T13:57:08","slug":"aniversario","status":"publish","type":"post","link":"http:\/\/www.ebc.gob.bo\/portal\/index.php\/2023\/10\/26\/aniversario\/","title":{"rendered":"LA EBC ENTREG\u00d3 M\u00c1S DE 30 OBRAS EN BENEFICIO DEL PUEBLO BOLIVIANO"},"content":{"rendered":"\n<div class=\"alignnormal\"><div id=\"metaslider-id-1676\" style=\"width: 100%;\" class=\"ml-slider-3-108-0 metaslider metaslider-flex metaslider-1676 ml-slider has-dots-nav ms-theme-default\" role=\"region\" aria-label=\"Aniversario\" data-height=\"300\" data-width=\"700\">\n    <div id=\"metaslider_container_1676\">\n        <div id=\"metaslider_1676\">\n            <ul class='slides'>\n                <li style=\"display: block; width: 100%;\" class=\"slide-1682 ms-image \" aria-roledescription=\"slide\" data-date=\"2023-10-26 20:13:40\" data-filename=\"IMG-20231026-WA0004-700x300.jpg\" data-slide-type=\"image\"><img fetchpriority=\"high\" decoding=\"async\" src=\"http:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2023\/10\/IMG-20231026-WA0004-700x300.jpg\" height=\"300\" width=\"700\" alt=\"\" class=\"slider-1676 slide-1682 msDefaultImage\" title=\"IMG-20231026-WA0004\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-1683 ms-image \" aria-roledescription=\"slide\" data-date=\"2023-10-26 20:13:41\" data-filename=\"IMG-20231026-WA0006-1-700x300.jpg\" data-slide-type=\"image\"><img decoding=\"async\" src=\"http:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2023\/10\/IMG-20231026-WA0006-1-700x300.jpg\" height=\"300\" width=\"700\" alt=\"\" class=\"slider-1676 slide-1683 msDefaultImage\" title=\"IMG-20231026-WA0006\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-1684 ms-image \" aria-roledescription=\"slide\" data-date=\"2023-10-26 20:13:43\" data-filename=\"IMG-20231026-WA0003-1-700x300.jpg\" data-slide-type=\"image\"><img decoding=\"async\" src=\"http:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2023\/10\/IMG-20231026-WA0003-1-700x300.jpg\" height=\"300\" width=\"700\" alt=\"\" class=\"slider-1676 slide-1684 msDefaultImage\" title=\"IMG-20231026-WA0003\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-1685 ms-image \" aria-roledescription=\"slide\" data-date=\"2023-10-26 20:13:45\" data-filename=\"IMG-20231026-WA0004-1-700x300.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2023\/10\/IMG-20231026-WA0004-1-700x300.jpg\" height=\"300\" width=\"700\" alt=\"\" class=\"slider-1676 slide-1685 msDefaultImage\" title=\"IMG-20231026-WA0004\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-1686 ms-image \" aria-roledescription=\"slide\" data-date=\"2023-10-26 20:13:46\" data-filename=\"IMG-20231026-WA0002-1-700x300.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2023\/10\/IMG-20231026-WA0002-1-700x300.jpg\" height=\"300\" width=\"700\" alt=\"\" class=\"slider-1676 slide-1686 msDefaultImage\" title=\"IMG-20231026-WA0002\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-1687 ms-image \" aria-roledescription=\"slide\" data-date=\"2023-10-26 20:13:46\" data-filename=\"IMG-20231026-WA0005-1-700x300.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2023\/10\/IMG-20231026-WA0005-1-700x300.jpg\" height=\"300\" width=\"700\" alt=\"\" class=\"slider-1676 slide-1687 msDefaultImage\" title=\"IMG-20231026-WA0005\" \/><\/li>\n            <\/ul>\n        <\/div>\n        \n    <\/div>\n<\/div><\/div>\n\n\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">La Empresa Estrat\u00e9gica Boliviana de Construcci\u00f3n y Conservaci\u00f3n de Infraestructura Civil (EBC) celebra 12 a\u00f1os de arduo trabajo y contribuci\u00f3n al desarrollo de Bolivia. Desde su creaci\u00f3n en 2011, la EBC se ha posicionado como l\u00edder en el sector de la construcci\u00f3n, ejecutando m\u00e1s de 30 proyectos y alcanzando una inversi\u00f3n total de m\u00e1s de 1.000 millones de bolivianos.<\/span><\/p>\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"http:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2023\/10\/IMG-20231026-WA0005-1-1024x576.jpg\" alt=\"\" class=\"wp-image-1681\" srcset=\"http:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2023\/10\/IMG-20231026-WA0005-1-1024x576.jpg 1024w, http:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2023\/10\/IMG-20231026-WA0005-1-300x169.jpg 300w, http:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2023\/10\/IMG-20231026-WA0005-1-768x432.jpg 768w, http:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2023\/10\/IMG-20231026-WA0005-1.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">La EBC ha sido fundamental en la construcci\u00f3n de infraestructura vial, edificaciones y obras p\u00fablicas en todo el territorio boliviano. Gracias a su labor, se han construido m\u00e1s de 281km de carreteras, mejorando la conectividad y facilitando el transporte de personas y mercanc\u00edas en diferentes regiones del pa\u00eds.<\/span><\/p>\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"http:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2023\/10\/IMG-20231026-WA0003-1-1024x683.jpg\" alt=\"\" class=\"wp-image-1678\" srcset=\"http:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2023\/10\/IMG-20231026-WA0003-1-1024x683.jpg 1024w, http:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2023\/10\/IMG-20231026-WA0003-1-300x200.jpg 300w, http:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2023\/10\/IMG-20231026-WA0003-1-768x512.jpg 768w, http:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2023\/10\/IMG-20231026-WA0003-1.jpg 1392w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Entre los proyectos m\u00e1s destacados ejecutados por la EBC se encuentran infraestructuras deportivas como el vel\u00f3dromo y la piscina ol\u00edmpica, as\u00ed como la sede de la Uni\u00f3n de Naciones Suramericanas (Unasur), carreteras como la doble v\u00eda industrial Viacha El Alto, la Hidrov\u00eda Ichilo Mamor\u00e9, aeropuertos de Guayaramer\u00edn, Riberalta, Rurrenabaque entre otros. Estas obras han representado una inversi\u00f3n de m\u00e1s de 400 millones de bolivianos, ahora est\u00e1n al servicio del pueblo boliviano y contribuyen a mejorar su calidad de vida.<\/span><\/p>\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"http:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2023\/10\/IMG-20231026-WA0002-1-1024x683.jpg\" alt=\"\" class=\"wp-image-1680\" srcset=\"http:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2023\/10\/IMG-20231026-WA0002-1-1024x683.jpg 1024w, http:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2023\/10\/IMG-20231026-WA0002-1-300x200.jpg 300w, http:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2023\/10\/IMG-20231026-WA0002-1-768x512.jpg 768w, http:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2023\/10\/IMG-20231026-WA0002-1.jpg 1392w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Adem\u00e1s, es importante resaltar que la inversi\u00f3n p\u00fablica en estas obras tambi\u00e9n ha tenido un impacto positivo en la econom\u00eda local, generando empleo y brindando oportunidades a los trabajadores y sus familias.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">En la actualidad, la EBC se encuentra trabajando en 10 obras de construcci\u00f3n en diferentes departamentos de Bolivia, como Tarija, Santa Cruz, Chuquisaca, Cochabamba, Beni y Pando. Estos proyectos, que representan una inversi\u00f3n superior a los 500 millones de bolivianos, tienen como objetivo mejorar la infraestructura vial y brindar mejores condiciones de vida a los habitantes de estas regiones.<\/span><\/p>\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"http:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2023\/10\/IMG-20231026-WA0006-1-1024x576.jpg\" alt=\"\" class=\"wp-image-1677\" srcset=\"http:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2023\/10\/IMG-20231026-WA0006-1-1024x576.jpg 1024w, http:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2023\/10\/IMG-20231026-WA0006-1-300x169.jpg 300w, http:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2023\/10\/IMG-20231026-WA0006-1-768x432.jpg 768w, http:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2023\/10\/IMG-20231026-WA0006-1.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n<p><span style=\"font-weight: 400;\">En este aniversario, la EBC agradece a todos los trabajadores y colaboradores que han sido parte fundamental de su \u00e9xito y contribuci\u00f3n al progreso de Bolivia. La empresa reafirma su compromiso de seguir trabajando por el desarrollo del pa\u00eds, impulsando proyectos de infraestructura que mejoren la calidad de vida de todos los bolivianos.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">El gerente general de la EBC, Ra\u00fal Vedia Zarate, destac\u00f3 el compromiso y el arduo trabajo realizado por la empresa en estos 12 a\u00f1os. Agradeci\u00f3 a todos los involucrados en el proceso y reafirm\u00f3 el compromiso de la EBC de seguir liderando en el sector de la construcci\u00f3n, promoviendo el crecimiento econ\u00f3mico y generando empleo para el beneficio de todo el pueblo boliviano.<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>La Empresa Estrat\u00e9gica Boliviana de Construcci\u00f3n y Conservaci\u00f3n de Infraestructura Civil (EBC) celebra 12 a\u00f1os de arduo trabajo y contribuci\u00f3n<\/p>\n","protected":false},"author":1,"featured_media":1681,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"gallery","meta":{"colormag_page_layout":"no_sidebar_content_centered","_joinchat":[],"footnotes":""},"categories":[17,10],"tags":[],"class_list":["post-1688","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-comunicacion","category-general","post_format-post-format-gallery"],"aioseo_notices":[],"_links":{"self":[{"href":"http:\/\/www.ebc.gob.bo\/portal\/index.php\/wp-json\/wp\/v2\/posts\/1688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.ebc.gob.bo\/portal\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.ebc.gob.bo\/portal\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.ebc.gob.bo\/portal\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.ebc.gob.bo\/portal\/index.php\/wp-json\/wp\/v2\/comments?post=1688"}],"version-history":[{"count":3,"href":"http:\/\/www.ebc.gob.bo\/portal\/index.php\/wp-json\/wp\/v2\/posts\/1688\/revisions"}],"predecessor-version":[{"id":1692,"href":"http:\/\/www.ebc.gob.bo\/portal\/index.php\/wp-json\/wp\/v2\/posts\/1688\/revisions\/1692"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.ebc.gob.bo\/portal\/index.php\/wp-json\/wp\/v2\/media\/1681"}],"wp:attachment":[{"href":"http:\/\/www.ebc.gob.bo\/portal\/index.php\/wp-json\/wp\/v2\/media?parent=1688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.ebc.gob.bo\/portal\/index.php\/wp-json\/wp\/v2\/categories?post=1688"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.ebc.gob.bo\/portal\/index.php\/wp-json\/wp\/v2\/tags?post=1688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}