{"id":3355,"date":"2024-06-11T16:45:11","date_gmt":"2024-06-11T20:45:11","guid":{"rendered":"http:\/\/www.ebc.gob.bo\/portal\/?p=3355"},"modified":"2024-06-11T16:47:14","modified_gmt":"2024-06-11T20:47:14","slug":"inicio-de-obras-de-la-construccion-del-puente-vehicular-jatun-jila-potosi","status":"publish","type":"post","link":"https:\/\/www.ebc.gob.bo\/portal\/index.php\/2024\/06\/11\/inicio-de-obras-de-la-construccion-del-puente-vehicular-jatun-jila-potosi\/","title":{"rendered":"INICIO DE OBRAS DE LA CONSTRUCCI\u00d3N DEL \u00abPUENTE VEHICULAR JATUN JILA\u00bb &#8211; POTOS\u00cd"},"content":{"rendered":"\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><\/figure>\n\n\n\n<div class=\"alignnormal\"><div id=\"metaslider-id-3340\" style=\"width: 100%;\" class=\"ml-slider-3-108-0 metaslider metaslider-flex metaslider-3340 ml-slider has-dots-nav ms-theme-default\" role=\"region\" aria-label=\"Puente Potos\u00ed Prensa\" data-height=\"450\" data-width=\"800\">\n    <div id=\"metaslider_container_3340\">\n        <div id=\"metaslider_3340\">\n            <ul class='slides'>\n                <li style=\"display: block; width: 100%;\" class=\"slide-3353 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-06-11 16:38:18\" data-filename=\"EBC-Puente-Potosi-15-1-800x450.jpg\" data-slide-type=\"image\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-15-1-800x450.jpg\" height=\"450\" width=\"800\" alt=\"\" class=\"slider-3340 slide-3353 msDefaultImage\" title=\"EBC-Puente-Potos\u00ed-15\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-3354 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-06-11 16:38:20\" data-filename=\"pixelcut-export-29-1-scaled-800x450.jpg\" data-slide-type=\"image\"><img decoding=\"async\" src=\"https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/pixelcut-export-29-1-scaled-800x450.jpg\" height=\"450\" width=\"800\" alt=\"\" class=\"slider-3340 slide-3354 msDefaultImage\" title=\"pixelcut-export (29)\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-3350 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-06-11 16:38:15\" data-filename=\"EBC-Puente-Potosi-9-800x450.jpg\" data-slide-type=\"image\"><img decoding=\"async\" src=\"https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-9-800x450.jpg\" height=\"450\" width=\"800\" alt=\"\" class=\"slider-3340 slide-3350 msDefaultImage\" title=\"EBC-Puente-Potos\u00ed-9\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-3348 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-06-11 16:38:12\" data-filename=\"EBC-Puente-Potosi-5-800x450.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-5-800x450.jpg\" height=\"450\" width=\"800\" alt=\"\" class=\"slider-3340 slide-3348 msDefaultImage\" title=\"EBC-Puente-Potos\u00ed-5\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-3349 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-06-11 16:38:13\" data-filename=\"EBC-Puente-Potosi-7-1-800x450.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-7-1-800x450.jpg\" height=\"450\" width=\"800\" alt=\"\" class=\"slider-3340 slide-3349 msDefaultImage\" title=\"EBC-Puente-Potos\u00ed-7\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-3351 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-06-11 16:38:16\" data-filename=\"EBC-Puente-Potosi-11-1-800x450.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-11-1-800x450.jpg\" height=\"450\" width=\"800\" alt=\"\" class=\"slider-3340 slide-3351 msDefaultImage\" title=\"EBC-Puente-Potos\u00ed-11\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-3352 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-06-11 16:38:17\" data-filename=\"EBC-Puente-Potosi-12-800x450.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-12-800x450.jpg\" height=\"450\" width=\"800\" alt=\"\" class=\"slider-3340 slide-3352 msDefaultImage\" title=\"EBC-Puente-Potos\u00ed-12\" \/><\/li>\n            <\/ul>\n        <\/div>\n        \n    <\/div>\n<\/div><\/div>\n\n\n<h6>\u00a0<\/h6>\n<h6 style=\"text-align: justify;\">San Pedro de Buena Vista, Charcas, Potos\u00ed &#8211; Con gran entusiasmo y orgullo, se marca un hito importante con el inicio de las obras de construcci\u00f3n del \u00abPuente Vehicular Jatun Jila\u00bb. Este anhelado proyecto, liderado por el Presidente Luis Arce, cuenta con una inversi\u00f3n del Gobierno nacional de m\u00e1s de 22,6 millones de bolivianos, destinados a mejorar la conectividad y la movilidad segura para los habitantes de la regi\u00f3n.<\/h6>\n<p>\u00a0<\/p>\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"http:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/pixelcut-export-29-1-1024x576.jpg\" alt=\"\" class=\"wp-image-3347\" style=\"width:484px;height:auto\" srcset=\"https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/pixelcut-export-29-1-1024x576.jpg 1024w, https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/pixelcut-export-29-1-300x169.jpg 300w, https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/pixelcut-export-29-1-768x432.jpg 768w, https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/pixelcut-export-29-1-scaled-800x450.jpg 800w, https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/pixelcut-export-29-1-scaled-620x349.jpg 620w, https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/pixelcut-export-29-1-scaled-400x225.jpg 400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n<h6>\u00a0<\/h6>\n<h6 style=\"text-align: justify;\">En la ceremonia de colocaci\u00f3n de la piedra fundamental, se cont\u00f3 con la presencia del ministro de Educaci\u00f3n, Omar Veliz Ramos, quien destac\u00f3 la importancia de este proyecto para fomentar el desarrollo econ\u00f3mico y social de la regi\u00f3n. Este puente permitir\u00e1 un flujo constante y seguro de veh\u00edculos, contribuyendo significativamente al desarrollo de la infraestructura vial y la calidad de vida de los pobladores.<\/h6>\n<p>\u00a0<\/p>\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"http:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-9-1024x576.jpg\" alt=\"\" class=\"wp-image-3343\" style=\"width:476px;height:auto\" srcset=\"https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-9-1024x576.jpg 1024w, https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-9-300x169.jpg 300w, https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-9-768x432.jpg 768w, https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-9-800x450.jpg 800w, https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-9-620x349.jpg 620w, https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-9-400x225.jpg 400w, https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-9.jpg 2032w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n<h6>\u00a0<\/h6>\n<h6 style=\"text-align: justify;\"><strong>CARACTER\u00cdSTICAS DE LA OBRA<\/strong><\/h6>\n<h6 style=\"text-align: justify;\">El Puente Vehicular Jatun Jila tendr\u00e1 una longitud total de 312 metros, distribuidos en cuatro tramos: dos de 66 metros y dos de 90 metros. Dise\u00f1ado para ser bidireccional, el puente incluir\u00e1 dos carriles, cada uno con un ancho de 3,50 metros, proporcionando un ancho total de plataforma de 7 metros. La capa de rodadura ser\u00e1 de cemento, garantizando durabilidad y resistencia al tr\u00e1fico vehicular.<\/h6>\n<p>\u00a0<\/p>\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"http:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-15-1-1024x576.jpg\" alt=\"\" class=\"wp-image-3346\" style=\"width:472px;height:auto\" srcset=\"https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-15-1-1024x576.jpg 1024w, https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-15-1-300x169.jpg 300w, https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-15-1-768x432.jpg 768w, https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-15-1-800x450.jpg 800w, https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-15-1-620x349.jpg 620w, https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-15-1-400x225.jpg 400w, https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-15-1.jpg 2032w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n<h6>\u00a0<\/h6>\n<h6 style=\"text-align: justify;\">El proyecto, que est\u00e1 siendo ejecutado por la Empresa Boliviana de la Construcci\u00f3n Civil (EBC), contratada por la Unidad de Proyectos Especiales (UPRE) del Ministerio de la Presidencia, se desarrollar\u00e1 en un plazo de 465 d\u00edas calendario. Durante este tiempo, se espera culminar esta importante obra que transformar\u00e1 la conectividad y mejorar\u00e1 la calidad de vida en la regi\u00f3n.<\/h6>\n<p>\u00a0<\/p>\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"http:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-12-1024x576.jpg\" alt=\"\" class=\"wp-image-3345\" style=\"width:488px;height:auto\" srcset=\"https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-12-1024x576.jpg 1024w, https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-12-300x169.jpg 300w, https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-12-768x432.jpg 768w, https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-12-800x450.jpg 800w, https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-12-620x349.jpg 620w, https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-12-400x225.jpg 400w, https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-12.jpg 2032w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n<h6>\u00a0<\/h6>\n<h6 style=\"text-align: justify;\">El Puente Vehicular Jatun Jila tendr\u00e1 un impacto positivo en el desarrollo productivo, social y cultural del municipio de San Pedro de Buena Vista, mejorando la conectividad vial, la calidad de vida de la poblaci\u00f3n, las oportunidades de desarrollo y empleo. Entre los beneficios destacados ser\u00e1n la facilitar\u00e1 la comunicaci\u00f3n entre comunidades, reduciendo tiempos de viaje y aumentando la accesibilidad, permitiendo un flujo m\u00e1s eficiente de productos, beneficiando a productores y comerciantes. Adem\u00e1s, que impulsar\u00e1 proyectos de infraestructura adicionales y fomentar\u00e1 el crecimiento y desarrollo sostenido en el norte de Potos\u00ed.<\/h6>\n<p>\u00a0<\/p>\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"http:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-4-1024x576.jpg\" alt=\"\" class=\"wp-image-3324\" style=\"width:480px;height:auto\" srcset=\"https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-4-1024x576.jpg 1024w, https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-4-300x169.jpg 300w, https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-4-768x432.jpg 768w, https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-4-800x450.jpg 800w, https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-4-620x349.jpg 620w, https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-4-400x225.jpg 400w, https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-4.jpg 2032w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n<h6>\u00a0<\/h6>\n<h6 style=\"text-align: justify;\"><strong>COMPROMISO CON EL DESARROLLO REGIONAL<\/strong><\/h6>\n<h6 style=\"text-align: justify;\">Este proyecto refleja el compromiso de la Empresa Boliviana de la Construcci\u00f3n Civil (EBC) con el desarrollo y bienestar de las comunidades de Potos\u00ed, fortaleciendo la infraestructura vial y contribuyendo al progreso integral de la regi\u00f3n.<\/h6>\n<p>\u00a0<\/p>\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"http:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-11-1-1024x576.jpg\" alt=\"\" class=\"wp-image-3344\" style=\"width:476px;height:auto\" srcset=\"https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-11-1-1024x576.jpg 1024w, https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-11-1-300x169.jpg 300w, https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-11-1-768x432.jpg 768w, https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-11-1-800x450.jpg 800w, https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-11-1-620x349.jpg 620w, https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-11-1-400x225.jpg 400w, https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2024\/06\/EBC-Puente-Potosi-11-1.jpg 2032w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 San Pedro de Buena Vista, Charcas, Potos\u00ed &#8211; Con gran entusiasmo y orgullo, se marca un hito importante con<\/p>\n","protected":false},"author":1,"featured_media":3358,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"gallery","meta":{"colormag_page_layout":"default_layout","_joinchat":[],"footnotes":""},"categories":[17,10],"tags":[],"class_list":["post-3355","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-comunicacion","category-general","post_format-post-format-gallery"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.ebc.gob.bo\/portal\/index.php\/wp-json\/wp\/v2\/posts\/3355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ebc.gob.bo\/portal\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ebc.gob.bo\/portal\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ebc.gob.bo\/portal\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ebc.gob.bo\/portal\/index.php\/wp-json\/wp\/v2\/comments?post=3355"}],"version-history":[{"count":1,"href":"https:\/\/www.ebc.gob.bo\/portal\/index.php\/wp-json\/wp\/v2\/posts\/3355\/revisions"}],"predecessor-version":[{"id":3356,"href":"https:\/\/www.ebc.gob.bo\/portal\/index.php\/wp-json\/wp\/v2\/posts\/3355\/revisions\/3356"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ebc.gob.bo\/portal\/index.php\/wp-json\/wp\/v2\/media\/3358"}],"wp:attachment":[{"href":"https:\/\/www.ebc.gob.bo\/portal\/index.php\/wp-json\/wp\/v2\/media?parent=3355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ebc.gob.bo\/portal\/index.php\/wp-json\/wp\/v2\/categories?post=3355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ebc.gob.bo\/portal\/index.php\/wp-json\/wp\/v2\/tags?post=3355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}