{"id":757,"date":"2024-12-24T10:14:00","date_gmt":"2024-12-24T14:14:00","guid":{"rendered":"https:\/\/www.ebc.gob.bo\/portal\/?p=757"},"modified":"2025-05-29T15:01:01","modified_gmt":"2025-05-29T19:01:01","slug":"puente-chimore-villa-tunari-tramo-iv-a-1","status":"publish","type":"post","link":"https:\/\/www.ebc.gob.bo\/portal\/index.php\/2024\/12\/24\/puente-chimore-villa-tunari-tramo-iv-a-1\/","title":{"rendered":"VILLA TUNARI &#8211; ICHILO"},"content":{"rendered":"\n<div class=\"alignnormal\"><div id=\"metaslider-id-748\" style=\"width: 100%;\" class=\"ml-slider-3-108-0 metaslider metaslider-flex metaslider-748 ml-slider has-dots-nav ms-theme-default\" role=\"region\" aria-label=\"Puente Chimor\u00e9-Villa Tunari Tramo IV-A-1\" data-height=\"432\" data-width=\"648\">\n    <div id=\"metaslider_container_748\">\n        <div id=\"metaslider_748\">\n            <ul class='slides'>\n                <li style=\"display: block; width: 100%;\" class=\"slide-5432 ms-image \" aria-roledescription=\"slide\" data-date=\"2025-05-29 14:57:42\" data-filename=\"Villatunari-8-scaled-648x432.jpg\" data-slide-type=\"image\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2025\/05\/Villatunari-8-scaled-648x432.jpg\" height=\"432\" width=\"648\" alt=\"\" class=\"slider-748 slide-5432 msDefaultImage\" title=\"Villatunari--8\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-5425 ms-image \" aria-roledescription=\"slide\" data-date=\"2025-05-29 14:57:34\" data-filename=\"Villatunari-1-scaled-648x432.jpg\" data-slide-type=\"image\"><img decoding=\"async\" src=\"https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2025\/05\/Villatunari-1-scaled-648x432.jpg\" height=\"432\" width=\"648\" alt=\"\" class=\"slider-748 slide-5425 msDefaultImage\" title=\"Villatunari--1\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-5426 ms-image \" aria-roledescription=\"slide\" data-date=\"2025-05-29 14:57:36\" data-filename=\"Villatunari-2-scaled-648x432.jpg\" data-slide-type=\"image\"><img decoding=\"async\" src=\"https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2025\/05\/Villatunari-2-scaled-648x432.jpg\" height=\"432\" width=\"648\" alt=\"\" class=\"slider-748 slide-5426 msDefaultImage\" title=\"Villatunari--2\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-5427 ms-image \" aria-roledescription=\"slide\" data-date=\"2025-05-29 14:57:38\" data-filename=\"Villatunari-3-scaled-648x432.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2025\/05\/Villatunari-3-scaled-648x432.jpg\" height=\"432\" width=\"648\" alt=\"\" class=\"slider-748 slide-5427 msDefaultImage\" title=\"Villatunari--3\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-5428 ms-image \" aria-roledescription=\"slide\" data-date=\"2025-05-29 14:57:39\" data-filename=\"Villatunari-4-scaled-648x432.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2025\/05\/Villatunari-4-scaled-648x432.jpg\" height=\"432\" width=\"648\" alt=\"\" class=\"slider-748 slide-5428 msDefaultImage\" title=\"Villatunari--4\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-5429 ms-image \" aria-roledescription=\"slide\" data-date=\"2025-05-29 14:57:39\" data-filename=\"Villatunari-5-scaled-648x432.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2025\/05\/Villatunari-5-scaled-648x432.jpg\" height=\"432\" width=\"648\" alt=\"\" class=\"slider-748 slide-5429 msDefaultImage\" title=\"Villatunari--5\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-5430 ms-image \" aria-roledescription=\"slide\" data-date=\"2025-05-29 14:57:40\" data-filename=\"Villatunari-6-scaled-648x432.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2025\/05\/Villatunari-6-scaled-648x432.jpg\" height=\"432\" width=\"648\" alt=\"\" class=\"slider-748 slide-5430 msDefaultImage\" title=\"Villatunari--6\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-5431 ms-image \" aria-roledescription=\"slide\" data-date=\"2025-05-29 14:57:41\" data-filename=\"Villatunari-7-scaled-648x432.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2025\/05\/Villatunari-7-scaled-648x432.jpg\" height=\"432\" width=\"648\" alt=\"\" class=\"slider-748 slide-5431 msDefaultImage\" title=\"Villatunari--7\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-5433 ms-image \" aria-roledescription=\"slide\" data-date=\"2025-05-29 14:57:43\" data-filename=\"Villatunari-9-scaled-648x432.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ebc.gob.bo\/portal\/wp-content\/uploads\/2025\/05\/Villatunari-9-scaled-648x432.jpg\" height=\"432\" width=\"648\" alt=\"\" class=\"slider-748 slide-5433 msDefaultImage\" title=\"Villatunari--9\" \/><\/li>\n            <\/ul>\n        <\/div>\n        \n    <\/div>\n<\/div><\/div>\n\n\n\n<p><strong>OBRAS COMPLEMENTARIAS DE EMERGENCIA Y MANTENIMIENTO VIAL DEL TRAMO CO04: VILLA TUNARI &#8211; ICHILO<br><\/strong><br><strong>\u00c1REA URBANA DE CHIMOR\u00c9 PROG. 284+600 A 286+300<\/strong><\/p>\n\n\n\n<p><strong>UBICACI\u00d3N:<\/strong><\/p>\n\n\n\n<p>Se encuentra ubicado en el Departamento de Cochabamba que conecta a las poblaciones de Chimor\u00e9, Senda III, Lauca E\u00f1e, Shinahota, San Isidro y del municipio de Villa Tunari.<\/p>\n\n\n\n<p><strong>INVERSI\u00d3N GLOBAL:<\/strong> Bs16.406.114,89. <\/p>\n\n\n\n<p><strong>ESTADO DE LA OBRA:<\/strong> Entregada el 24 de diciembre de 2024.<\/p>\n\n\n\n<p><strong>FINANCIAMIENTO:<\/strong>&nbsp;Tesoro General de la Naci\u00f3n &#8211; TGN.<\/p>\n\n\n\n<p><strong>DESCRIPCI\u00d3N DEL PROYECTO<\/strong>:<\/p>\n\n\n\n<p>La construcci\u00f3n de las obras complementarias y el mantenimiento en el tramo CO04 se divide en los siguientes puntos claves: <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Pasarela Senda VI, tramo CO04: Villa Tunari \u2013 Ichilo.&nbsp; Accesos de ingreso y salida en el Viaducto N\u00b01, tramo CO04: Villa Tunari \u2013 Ichilo. <\/li>\n\n\n\n<li>Mantenimiento y obras de emergencia, tramo CO04: doble v\u00eda Puente Chimor\u00e9 \u2013 Villa Tunari, tramo IV \u2013 A \u2013 1, \u00e1rea urbana de Chimor\u00e9, Prog. 284+600 \u2013 Prog. 286+300.<\/li>\n<\/ul>\n\n\n\n<p><strong>ENTIDAD CONTRATANTE:<\/strong> Administradora Boliviana de Carreteras \u2013 ABC.<\/p>\n\n\n\n<p><strong>LOGROS REALIZADOS:<\/strong><\/p>\n\n\n\n<p>Se alcanz\u00f3 a: Iniciar los trabajos de mantenimiento de la v\u00eda en el \u00e1rea urbana de Chimor\u00e9. Se ha consolidado el dise\u00f1o final de la pasarela Senda IV. Se ha elaborado el dise\u00f1o final del viaducto Ivirgarzama.<\/p>\n\n\n\n<p><strong>IMPACTO:<\/strong><\/p>\n\n\n\n<p>La ejecuci\u00f3n de las Obras Complementarias de Emergencia y Mantenimiento Vial, Tramo Co04: Villa Tunari \u2013 Ichilo, es imprescindible para optimar el tr\u00e1fico vehicular y materializar la vinculaci\u00f3n entre las poblaciones de la provincia Carrasco, Chapare y departamentos de Cochabamba y Santa Cruz. Este mejoramiento beneficiar\u00e1 a la sociedad del entorno, en funci\u00f3n que las mismas cuenten con una mejor vinculaci\u00f3n y el flujo de comercializaci\u00f3n sea regular a lo largo del a\u00f1o, en pos de mejorar las condiciones de vida y desarrollo del sector.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>OBRAS COMPLEMENTARIAS DE EMERGENCIA Y MANTENIMIENTO VIAL DEL TRAMO CO04: VILLA TUNARI &#8211; ICHILO\u00c1REA URBANA DE CHIMOR\u00c9 PROG. 284+600 A<\/p>\n","protected":false},"author":1,"featured_media":5423,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"colormag_page_layout":"no_sidebar_content_centered","_joinchat":[],"footnotes":""},"categories":[10,2],"tags":[],"class_list":["post-757","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-general","category-business","post_format-post-format-gallery"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.ebc.gob.bo\/portal\/index.php\/wp-json\/wp\/v2\/posts\/757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ebc.gob.bo\/portal\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ebc.gob.bo\/portal\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ebc.gob.bo\/portal\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ebc.gob.bo\/portal\/index.php\/wp-json\/wp\/v2\/comments?post=757"}],"version-history":[{"count":6,"href":"https:\/\/www.ebc.gob.bo\/portal\/index.php\/wp-json\/wp\/v2\/posts\/757\/revisions"}],"predecessor-version":[{"id":5435,"href":"https:\/\/www.ebc.gob.bo\/portal\/index.php\/wp-json\/wp\/v2\/posts\/757\/revisions\/5435"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ebc.gob.bo\/portal\/index.php\/wp-json\/wp\/v2\/media\/5423"}],"wp:attachment":[{"href":"https:\/\/www.ebc.gob.bo\/portal\/index.php\/wp-json\/wp\/v2\/media?parent=757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ebc.gob.bo\/portal\/index.php\/wp-json\/wp\/v2\/categories?post=757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ebc.gob.bo\/portal\/index.php\/wp-json\/wp\/v2\/tags?post=757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}